{"id":32,"date":"2022-03-04T11:54:31","date_gmt":"2022-03-04T10:54:31","guid":{"rendered":"https:\/\/stimcareonline.com\/?page_id=32"},"modified":"2022-04-20T21:09:25","modified_gmt":"2022-04-20T19:09:25","slug":"conditions-generales-de-ventes","status":"publish","type":"page","link":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/","title":{"rendered":"Termini e condizioni di vendita"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"32\" class=\"elementor elementor-32\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea16756 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea16756\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d2bf86\" data-id=\"9d2bf86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9262afc elementor-widget elementor-widget-text-editor\" data-id=\"9262afc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header class=\"entry-header\"><h1 class=\"entry-title\">\u00a0<\/h1><h1>Condizioni generali di vendita<\/h1><p>\u00a0<\/p><\/header><div class=\"entry-content\"><p><strong>INFORMATIVA SULLA PRIVACY<\/strong><\/p><p><strong>In vigore il 24\/01\/2020<\/strong><\/p><p>Le presenti condizioni generali di vendita (\u00a0<strong>TERMINI E CONDIZIONI GENERALI\u00a0<\/strong>\") si applicano a tutti gli ordini e le consegne di prodotti (il \"\u00a0<strong>Prodotti\u00a0<\/strong>) realizzati da TORTEL INDUTRIES ai propri clienti (di seguito il \"Cliente\").\u00a0<strong>Cliente\u00a0<\/strong>\").<\/p><p>Il Cliente e il Fornitore sono di seguito indicati collettivamente come \"Parti\" o singolarmente come \"Parte\".<\/p><p>Le presenti Condizioni Generali di Vendita sono espressamente approvate e accettate senza riserve dal Cliente, il quale, con l'accettazione dell'offerta e la firma o l'invio del modulo d'ordine o del contratto, dichiara e riconosce di averne piena conoscenza, rinunciando in tal modo a fare affidamento su qualsiasi altro documento da lui emesso e, in particolare, sulle proprie condizioni generali di acquisto, che saranno inopponibili a TORTEL INDUSTRIES, anche se ne \u00e8 stata messa a conoscenza.<\/p><p>Qualsiasi deroga alle presenti condizioni generali di vendita deve essere espressamente accettata da TORTEL INDUSTRIES.<\/p><h4 class=\"has-text-align-left\"><strong>1. OFFERTA<\/strong><\/h4><p>TORTEL INDUSTRIES formula un'offerta indicativa indicando in particolare la quantit\u00e0, il prezzo, il periodo di esecuzione, l'imballaggio e le condizioni logistiche.<\/p><p>In caso di accettazione da parte del Cliente, TORTEL INDUSTRIES emetter\u00e0 una conferma scritta che definisce i termini e le condizioni dell'accordo tra TORTEL INDUSTRIES e il Cliente (di seguito denominata \"Conferma\").\u00a0<strong>Conferma dell'ordine<\/strong>\u00a0\").<\/p><p>La presente Conferma d'Ordine costituisce un impegno di TORTEL INDUSTRIES a consegnare i Prodotti. \u00a0<\/p><h4><strong>2. CONDIZIONI DI PREZZO<\/strong><\/h4><p>I prezzi sono quelli determinati alla data della Conferma d'Ordine da parte di TORTEL INDUSTRIES, salvo diverso accordo tra il Cliente e TORTEL INDUSTRIES.<\/p><p>I prezzi si intendono al netto di tutte le imposte e tasse (IVA, ecc.) e si riferiscono a un determinato prodotto, periodo, volume, imballaggio e condizioni logistiche.<\/p><p>Qualsiasi variazione dell'aliquota IVA si rifletter\u00e0 sul giorno di applicazione della nuova aliquota.<\/p><p>I prezzi escludono inoltre i costi di trasporto, imballaggio, scarico, assicurazione, tasse, oneri e diritti di propriet\u00e0 intellettuale, salvo diverso accordo tra il Cliente e TORTEL INDUSTRIES.<\/p><p>I servizi forniti da TORTEL INDUSTRIES che non sono esplicitamente previsti nella Conferma d'Ordine o nel Contratto e nelle presenti Condizioni Generali di Vendita saranno fatturati in aggiunta al Cliente.<\/p><p>Il Cliente sar\u00e0 l'unico responsabile e dovr\u00e0 pagare tutte le imposte, i dazi, le tasse e gli oneri, di qualsiasi natura, imposti da qualsiasi autorit\u00e0 governativa o amministrazione o da qualsiasi altra persona, in relazione ai Prodotti.<\/p><h4><strong>3. ORDINE<\/strong><\/h4><p>Per Ordine si intende qualsiasi richiesta di un Prodotto fatta dal Cliente a TORTEL INDUSTRIES, che diventa definitiva una volta confermata per iscritto da qualsiasi persona dotata di autorit\u00e0 all'interno di TORTEL INDUSTRIES, per mezzo di una Conferma d'Ordine (\"Conferma d'Ordine\").\u00a0<strong>Ordini<\/strong>\u00a0\").<\/p><p>TORTEL INDUSTRIES si riserva il diritto di accettare o rifiutare, in tutto o in parte, qualsiasi richiesta di Prodotto da parte del Cliente, in particolare in considerazione del volume e\/o dell'importo dell'ordine.<\/p><p>Salvo accettazione scritta da parte di TORTEL INDUSTRIES, nessun Ordine potr\u00e0 essere modificato dopo l'accettazione da parte di TORTEL INDUSTRIES.<\/p><p>TORTEL INDUSTRIES sar\u00e0 tenuta a soddisfare le richieste del Cliente solo nei limiti delle previsioni di vendita delle proprie scorte e capacit\u00e0 produttive, fermo restando che potr\u00e0 procedere per consegne parziali o disponibilit\u00e0. Nessun risarcimento potr\u00e0 essere richiesto dal Cliente in caso di carenza di scorte o limitazioni di consegna.<\/p><h4><strong>4. CONSEGNA<\/strong><\/h4><p>La consegna viene effettuata da qualsiasi magazzino esterno in cui si trovino i Prodotti, salvo diverso accordo tra il Cliente e TORTEL INDUSTRIES.<\/p><p>Pertanto, la consegna dei Prodotti al Cliente si riterr\u00e0 effettuata nel momento in cui i Prodotti saranno messi a disposizione del Cliente da TORTEL INDUSTRIES nei locali di TORTEL INDUSTRIES o in qualsiasi magazzino esterno in cui si trovino i Prodotti, scaricati.<\/p><p>I tempi e le date di consegna sono concordati tra TORTEL INDUSTRIES e il Cliente nella Conferma d'Ordine.<\/p><p>Se non diversamente stabilito, per ogni consegna risultante da un Ordine \u00e8 possibile registrare un solo luogo di consegna, una sola persona giuridica fatturata, una sola data e un solo modo di trasporto.<\/p><p>Salvo diverso accordo tra il Cliente e TORTEL INDUSTRIES, per ogni Ordine, la consegna sar\u00e0 effettuata in un'unica operazione durante le ore diurne dal luned\u00ec al venerd\u00ec, con carico e scarico a carico del destinatario.<\/p><p>I tempi di consegna sono forniti a titolo puramente indicativo e il mancato rispetto di tali tempi non potr\u00e0 dar luogo a danni, detrazioni o penali e non dar\u00e0 diritto al Cliente di rifiutare i Prodotti.<\/p><p>TORTEL INDUSTRIES si riserva il diritto di consegnare le quantit\u00e0 ordinate per ogni consegna e fatturer\u00e0 il prezzo corrispondente alla quantit\u00e0 consegnata.<\/p><h4><strong>5. ACCOGLIENZA - RECLAMI<\/strong><\/h4><p>I Prodotti consegnati sono conformi alle specifiche di TORTEL INDUSTRIES descritte nella scheda tecnica messa a disposizione del Cliente su richiesta di TORTEL INDUSTRIES (la \"Scheda Tecnica\").\u00a0<strong>Dati tecnici<\/strong>\u00a0\"Prima del carico, TORTEL INDUSTRIES verificher\u00e0 la qualit\u00e0 dei Prodotti nei propri magazzini o in qualsiasi magazzino esterno in cui si trovino i Prodotti.<\/p><p>Qualsiasi altro reclamo relativo alla natura, alla qualit\u00e0 o all'imballaggio della merce consegnata dovr\u00e0 essere inviato a TORTEL INDUSTRIES immediatamente e al pi\u00f9 tardi entro ventiquattro (24) ore dalla messa a disposizione della merce. Allo scadere di tali termini, l'intera consegna o fornitura si riterr\u00e0 effettuata in conformit\u00e0 all'Ordine e sar\u00e0 considerata conforme all'Ordine sotto tutti i punti di vista.<\/p><p>Ogni reclamo deve essere debitamente giustificato dal Cliente, che deve immediatamente fornire a TORTEL INDUSTRIES i mezzi per verificare lo stato della merce in questione e trasmettere a TORTEL INDUSTRIES ogni elemento necessario per verificare il reclamo. Di conseguenza, il Cliente deve astenersi dall'intervenire personalmente o far intervenire terzi per porre rimedio alla situazione prima che TORTEL INDUSTRIES sia stata in grado di accertare i presunti difetti.<\/p><h4><strong>6. RITORNO<\/strong><\/h4><p>Non saranno accettate restituzioni di merce senza l'espresso consenso di TORTEL INDUSTRIES.<\/p><p>I costi e i rischi della restituzione della merce saranno sempre a carico del Cliente.<\/p><p>La merce restituita deve essere accompagnata da una nota di reso e deve essere nelle condizioni in cui TORTEL INDUSTRIES l'ha consegnata.<\/p><h4><strong>7 STOCCAGGIO<\/strong><\/h4><p>Oltre alle istruzioni speciali che possono apparire nella scheda di sicurezza fornita da TORTEL INDUSTRIES, la merce deve essere immagazzinata al chiuso in un luogo fresco e asciutto, al riparo dalla luce, dalla polvere, dall'acqua, dalle intemperie e dal gelo, e in condizioni sanitarie prive di roditori o insetti. La merce non deve essere conservata in condizioni anomale o incompatibili con la sua natura, n\u00e9 in prossimit\u00e0 di altri prodotti fortemente odorosi come detergenti, pneumatici o carburanti.<\/p><h4><strong>8. FATTURAZIONE - PAGAMENTO<\/strong><\/h4><p>Le fatture vengono emesse e datate il giorno in cui i Prodotti vengono caricati dai magazzini di TORTEL INDUSTRIES o da qualsiasi magazzino esterno in cui si trovino i Prodotti.<\/p><p>Se non diversamente concordato, le fatture sono pagabili entro trenta (30) giorni dalla data della fattura tramite bonifico bancario alle coordinate bancarie fornite da TORTEL INDUSTRIES. Il pagamento si considera effettuato alla data in cui i fondi sono messi a disposizione di TORTEL INDUSTRIES.<\/p><p>In via eccezionale, nel caso di una prima conferma d'ordine tra il Cliente e TORTEL INDUSTRIES, verr\u00e0 richiesto un pagamento anticipato prima di qualsiasi consegna della merce.<\/p><p>Le fatture sono redatte in due esemplari originali (cartacei o dematerializzati se richiesto dal Cliente), di cui uno destinato al Cliente e uno conservato da TORTEL INDUSTRIES e devono contenere tutte le informazioni richieste dalla legge e in particolare dall'articolo L.441-3 del Codice di Commercio francese.<\/p><p>In caso di mancato pagamento parziale o totale alla data di scadenza, TORTEL INDUSTRIES si riserva il diritto di esigere :<\/p><ul><li>Le penali per i ritardi di pagamento sono calcolate dalla data di scadenza alla data di effettivo pagamento completo a un tasso pari a tre volte il tasso di interesse legale o al 10% dell'importo non pagato, se superiore;<\/li><li>Un'indennit\u00e0 fissa per le spese di incasso, il cui importo \u00e8 fissato per decreto (40 euro) (art. D441-5 del Codice commerciale francese);<\/li><li>Pagamento immediato delle somme dovute dal Cliente e pagamento in contanti per le vendite future;<\/li><li>Sospensione delle consegne fino al completo pagamento del prezzo, senza pregiudizio per qualsiasi altra azione.<\/li><\/ul><p>TORTEL INDUSTRIES si riserva il diritto, a sua esclusiva discrezione, in particolare nel caso in cui il Cliente presenti un rischio di insolvenza, di modificare i termini di pagamento concordati, di richiedere il pagamento immediato delle fatture insolute, di limitare gli importi insoluti, di richiedere il pagamento prima della consegna dei Prodotti o qualsiasi altra forma di garanzia di pagamento.<\/p><p>Nessun reclamo relativo a fatture di Prodotti TORTEL INDUSTRIES pu\u00f2 essere presentato a TORTEL INDUSTRIES dopo un periodo di dodici (12) mesi dalla data di emissione di tali fatture.<\/p><p>Qualsiasi reclamo relativo alle fatture deve essere accompagnato dai documenti giustificativi necessari per verificarne la fondatezza.<\/p><p>Se non diversamente concordato, non saranno concessi sconti per il pagamento anticipato delle nostre fatture.<\/p><h4><strong>\u00a0 9. RISERVA DI PROPRIET\u00c0 - RIVENDITA O CONVERSIONE<\/strong><\/h4><p><strong><u>Riserva di propriet\u00e0<\/u><\/strong><strong>\u00a0- I Prodotti venduti restano di propriet\u00e0 di TORTEL INDUSTRIES fino al completo pagamento del prezzo di vendita, degli interessi, delle spese e degli accessori. In caso di mancato pagamento da parte del Cliente, TORTEL INDUSTRIES potr\u00e0 riprendere possesso dei Prodotti non pagati, anche in caso di procedura collettiva contro il Cliente ai sensi degli articoli L 624-16 e seguenti del Codice di Commercio francese.<\/strong><\/p><p><strong>La vendita sar\u00e0 automaticamente annullata se TORTEL INDUSTRIES lo riterr\u00e0 opportuno e gli eventuali pagamenti anticipati gi\u00e0 effettuati saranno trattenuti da TORTEL INDUSTRIES in cambio dell'utilizzo dei Prodotti da parte del Cliente.<\/strong><\/p><p><strong>Il ritiro dei Prodotti non esclude altre azioni legali che TORTEL INDUSTRIES pu\u00f2 intraprendere. Tutti i costi del pignoramento e\/o del procedimento saranno a carico del Cliente.<\/strong><\/p><p><strong><u>Rivendita o conversione<\/u><\/strong><strong>\u00a0- I Prodotti rimangono di propriet\u00e0 di TORTEL INDUSTRIES fino al ricevimento del pagamento completo e il Cliente non pu\u00f2 disporre dei Prodotti per la rivendita o la lavorazione. Tuttavia, TORTEL INDUSTRIES autorizza il Cliente a rivendere i Prodotti solo per scopi commerciali, a condizione che il Cliente paghi l'intero prezzo dei Prodotti al momento della rivendita.<\/strong><\/p><h4><strong>10. GARANZIA - ESCLUSIONE DELLA GARANZIA<\/strong><\/h4><p>Il Cliente dichiara di essere competente a valutare i Prodotti.<\/p><p>Il Cliente riconosce di essere stato pienamente informato delle caratteristiche dei Prodotti e degli obiettivi che possono essere raggiunti utilizzando i Prodotti. TORTEL INDUSTRIES non pu\u00f2 garantire che i Prodotti siano adatti a qualsiasi scopo particolare.<\/p><p>Il Cliente deve fare un uso corretto dei Prodotti, secondo le buone pratiche e in conformit\u00e0 con la Scheda Tecnica fornita con i Prodotti. Tutte le istruzioni devono essere rispettate, pena la decadenza delle garanzie fornite nel presente articolo.<\/p><p>In ogni caso e nonostante qualsiasi disposizione contraria, TORTEL INDUSTRIES sar\u00e0 responsabile di eventuali vizi occulti dei Prodotti in conformit\u00e0 alle disposizioni degli articoli 1641 e seguenti del Codice Civile francese.<\/p><p>In caso di Prodotti difettosi, si applicano le disposizioni degli articoli 1245 e seguenti del Codice Civile francese.<\/p><p>Salvo diverso accordo tra il Cliente e TORTEL INDUSTRIES, TORTEL INDUSTRIES garantisce i Prodotti per la durata della data di scadenza.<\/p><p>Per i prodotti non fabbricati da TORTEL INDUSTRIES, TORTEL INDUSTRIES trasmetter\u00e0 solo la garanzia del fornitore.<\/p><p>Non viene fornita alcuna garanzia diversa da quelle sopra menzionate. TORTEL INDUSTRIES non garantisce che il Prodotto soddisfi i requisiti del Cliente o che funzioni in combinazioni diverse da quelle specificate nella Scheda Tecnica.<\/p><p>Qualsiasi garanzia \u00e8 esclusa in caso di difetto apparente, uso improprio, negligenza o mancanza di manutenzione o conservazione da parte del Cliente, o mancanza di informazioni da parte del Cliente sull'ambiente specifico in cui viene utilizzato il Prodotto, cos\u00ec come in caso di normale usura o forza maggiore, o da una modifica dei Prodotti non prevista o specificata da TORTEL INDUSTRIES e infine in caso di utilizzo dopo la data di scadenza.<\/p><p>Per far valere i propri diritti, il Cliente deve informare TORTEL INDUSTRIES, per iscritto, dell'esistenza dei difetti con le opportune giustificazioni, entro un termine massimo di quindici (15) giorni dalla loro scoperta.<\/p><p>In base alla disponibilit\u00e0 di magazzino, la garanzia di TORTEL INDUSTRIES si limita alla sostituzione, entro un termine ragionevole, nella migliore delle ipotesi entro quindici (15) giorni, dei Prodotti in garanzia ritenuti difettosi, senza che TORTEL INDUSTRIES possa richiedere alcun altro tipo di risarcimento, inclusi, ma non solo, i danni.<\/p><p>Se non diversamente indicato, la sostituzione dei Prodotti non avr\u00e0 l'effetto di estendere la durata del periodo di garanzia.<\/p><p>In caso di uso improprio dei Prodotti da parte del Cliente e che richieda la restituzione a TORTEL INDUSTRIES, le spese di trasporto saranno a carico del Cliente.<\/p><p>Nessun consiglio o informazione fornita da TORTEL INDUSTRIES, dai suoi venditori, distributori, agenti o dipendenti creer\u00e0 una nuova garanzia o estender\u00e0 la garanzia di cui alla presente clausola e il Cliente non dovr\u00e0 fare affidamento su tali consigli o informazioni.<\/p><h4><strong>11. PROPRIET\u00c0 INTELLETTUALE<\/strong><\/h4><p>Il Cliente riconosce di non avere alcun diritto sui diritti di propriet\u00e0 intellettuale e in particolare sui marchi, nomi commerciali, modelli, brevetti, immagini, loghi, denominazioni sociali, know-how, ricette e specifiche tecniche relative ai Prodotti venduti al Cliente e che sono e restano di propriet\u00e0 esclusiva di TORTEL INDUSTRIES.<\/p><p>Salvo previo consenso scritto di TORTEL INDUSTRIES, il Cliente si impegna a non utilizzare e\/o sfruttare in alcun modo e a qualsiasi titolo i diritti di propriet\u00e0 intellettuale di TORTEL INDUSTRIES.<\/p><p>Il Cliente si impegna a informare TORTEL INDUSTRIES non appena venga a conoscenza di qualsiasi atto di concorrenza sleale o di qualsiasi violazione dei diritti di propriet\u00e0 intellettuale di TORTEL INDUSTRIES o di qualsiasi contestazione da parte di un terzo che sostenga che la merce viola i suoi diritti di propriet\u00e0 intellettuale.<\/p><h4><strong>12. FORZA MAGGIORE<\/strong><\/h4><p>Qualsiasi evento al di fuori del controllo del debitore, che non poteva essere ragionevolmente previsto al momento dell'emissione della Conferma d'Ordine e i cui effetti non possono essere evitati con misure appropriate, che impedisca l'esecuzione di tutto o parte dell'Ordine, sar\u00e0 considerato un evento di forza maggiore, in particolare qualsiasi incidente che influisca sulla produzione o sullo stoccaggio dei Prodotti, il guasto del vettore, l'incendio, l'esplosione, l'inondazione, il guasto dei macchinari, gli scioperi parziali o totali, l'azione di un cliente, di un fornitore o di terzi, qualsiasi guerra civile o straniera o altri disordini politici o sanitari.<\/p><p>Questi eventi, anche se prevedibili, sospenderanno o estingueranno, a seconda dei casi, le obbligazioni del debitore, e lo stesso varr\u00e0 quando questi eventi sono di natura tale da rendere economicamente esorbitante l'adempimento degli impegni.<\/p><h4><strong>13. LIMITAZIONE DI RESPONSABILIT\u00c0<\/strong><\/h4><p>TORTEL INDUSTRIES sar\u00e0 responsabile solo delle conseguenze economiche di (i) qualsiasi danno diretto e (ii) prevedibile causato dai Prodotti.<\/p><p>In nessun caso TORTEL INDUSTRIES sar\u00e0 responsabile di perdite o danni indiretti o conseguenti, inclusi, ma non limitati a, perdita di profitti, perdita di affari, perdita di immagine, perdita di entrate o profitti, perdita di avviamento, perdita di opportunit\u00e0, costi di approvvigionamento di prodotti sostitutivi, in relazione o derivanti dal prodotto, dalla sua installazione se effettuata da TORTEL INDUSTRIES, o dal suo funzionamento.<\/p><p>In ogni caso, l'importo della responsabilit\u00e0 di TORTEL INDUSTRIES derivante dall'uso o dal livello di prestazioni del Prodotto \u00e8 limitato all'importo del rimborso delle somme effettivamente pagate dal Cliente a TORTEL INDUSTRIES.<\/p><h4><strong>14. AUTONOMIA DELLE DISPOSIZIONI<\/strong><\/h4><p>In caso di domande, commenti, reclami o richieste relative alla presente politica sui cookie o al trattamento dei vostri dati personali, potete contattarci al seguente indirizzo:\u00a0<a href=\"mailto:contact@stimcareonline.com\">contact@stimcareonline.com<\/a>\u00a0<\/p><h4><strong>15. AUTONOMIA DELLE DISPOSIZIONI<\/strong><\/h4><p>La rinuncia da parte di una delle Parti a qualsiasi violazione o inadempimento di una qualsiasi disposizione dei presenti Termini e condizioni generali non costituir\u00e0 o sar\u00e0 interpretata come una rinuncia a qualsiasi successiva violazione o inadempimento.<\/p><p>Se una delle clausole delle presenti condizioni generali di vendita \u00e8 ritenuta o dichiarata illegale, nulla o inapplicabile, o contraria alle leggi e ai regolamenti, la validit\u00e0 delle altre clausole non sar\u00e0 in alcun modo compromessa.<\/p><hr class=\"wp-block-separator\" \/><h4><strong>16. RISERVATEZZA<\/strong><\/h4><p>Il Cliente non potr\u00e0 rivelare, divulgare o trasferire a terzi, senza il consenso scritto di TORTEL INDUSTRIES, alcuna informazione ottenuta direttamente o indirettamente da TORTEL INDUSTRIES o in relazione agli ordini di Prodotti, ivi compresi, a titolo esemplificativo e non esaustivo, le attivit\u00e0 o i metodi tecnici o commerciali di TORTEL INDUSTRIES e, in particolare, i prezzi, gli sconti, i prodotti, le specifiche dei prodotti, i processi, i dati e il know-how, le idee, le informazioni tecniche di qualsiasi tipo.<\/p><p>Per quanto riguarda le informazioni coperte da segreto aziendale ai sensi della Legge n. 2018-670 del 30 luglio 2018, esse devono rimanere riservate fino a quando non vengono rese pubbliche dal legittimo titolare o da terzi diversi dalle Parti.<\/p><h4><strong>17. DATI PERSONALI<\/strong><\/h4><p><a>Nell'ambito del presente rapporto contrattuale, TORTEL INDUSTRIES pu\u00f2 raccogliere e trattare i dati personali relativi al personale del Cliente: cognome, nome, indirizzo postale, indirizzo e-mail, numero di telefono (di seguito denominati \"dati personali del Cliente\").\u00a0<strong>Dati personali<\/strong>\u00a0\").<\/a><\/p><p>In qualit\u00e0 di titolare del trattamento, TORTEL INDUSTRIES si impegna a rispettare gli obblighi previsti dalla normativa francese in materia di dati personali, in particolare le disposizioni della legge n. 78-17 del 6 gennaio 1978, nota come \"legge sulla protezione dei dati\", modificata dalla legge 2004-801 del 6 agosto 2004, e il regolamento (UE) 2016\/679 del Parlamento europeo e del Consiglio, del 27 aprile 2016, sulla protezione dei dati, entrato in vigore il 25 maggio 2018 (di seguito \"regolamento sulla protezione dei dati\").\u00a0<strong>Regolamenti<\/strong>\u00a0\"). TORTEL INDUSTRIES potr\u00e0 trattare i Dati Personali strettamente necessari (i) per gestire l'ordine e, pi\u00f9 in generale, il rapporto commerciale, e\/o (ii) per gestire i pagamenti in sospeso ed eventuali controversie, e\/o (iii) per adempiere ai propri obblighi legali e normativi.\u00a0<a>I dati personali sono destinati all'uso da parte di TORTEL INDUSTRIES e dei dipartimenti esterni responsabili dell'adempimento degli obblighi sociali, contabili e fiscali, nonch\u00e9 di eventuali altri subappaltatori coinvolti nel rapporto commerciale.<\/a>. Sono conservati per il tempo strettamente necessario alle finalit\u00e0 di cui sopra.<\/p><p>Il personale del Cliente ha il diritto di accedere, rettificare, opporsi, cancellare, limitare e richiedere i Dati personali forniti a TORTEL INDUSTRIES, in un formato strutturato, comunemente utilizzato e leggibile da una macchina, al fine di trasmetterli a un altro titolare del trattamento. Qualsiasi richiesta di questo tipo deve essere indirizzata alla direzione di TORTEL INDUSTRIES.<\/p><p>In caso di violazione dei Dati Personali, suscettibile di comportare un rischio per i diritti e le libert\u00e0 del personale interessato, TORTEL INDUSTRIES si impegna a notificare, alle condizioni di cui agli articoli 33 e 34 del Regolamento, la violazione in questione all'autorit\u00e0 di controllo competente (CNIL) entro 72 ore dal momento in cui ne \u00e8 venuta a conoscenza, e all'interessato il prima possibile. Fatto salvo qualsiasi altro rimedio amministrativo o giudiziario, se il personale del Cliente ritiene che il trattamento dei suoi Dati personali costituisca una violazione delle disposizioni della legislazione in vigore, pu\u00f2 presentare un reclamo alla CNIL.<\/p><h4><strong>18. ETICA - CONFORMIT\u00c0 ALLE NORMATIVE<\/strong><\/h4><p>Nel corso del rapporto contrattuale con il Cliente, TORTEL INDUSTRIES si impegna a rispettare tutti gli obblighi legali e normativi in vigore, in particolare in materia di diritto del lavoro, immigrazione, sicurezza sociale, salute, sicurezza e ambiente.<\/p><p>TORTEL INDUSTRIES garantisce espressamente, pena l'immediata risoluzione del rapporto contrattuale a suo esclusivo danno, di impiegare esclusivamente personale dipendente nel rispetto della legislazione che regola i rapporti di lavoro e il mercato del lavoro.<\/p><p>TORTEL INDUSTRIES non utilizzer\u00e0 :<\/p><ul><li>il lavoro minorile, come definito in particolare dalla Convenzione dell'Organizzazione Internazionale del Lavoro del 26 giugno 1973 sull'abolizione del lavoro minorile, che fissa a quindici anni l'et\u00e0 minima per l'ammissione all'impiego o al lavoro (artt. 1 e 2-3), fatte salve le disposizioni pi\u00f9 favorevoli della legislazione nazionale;<\/li><li>il lavoro di persone sottoposte a lavoro forzato, come definito dalla Convenzione dell'Organizzazione Internazionale del Lavoro del 28 giugno 1930 sull'abolizione del lavoro forzato o obbligatorio, e di persone detenute per qualsiasi motivo;<\/li><li>il lavoro di persone sottoposte a uno stato di servit\u00f9 o di schiavit\u00f9, come definito e vietato in particolare dal Patto internazionale sui diritti civili e politici del 16 dicembre 1966 e dalla Convenzione europea dei diritti dell'uomo del 4 novembre 1950 e, in generale, di persone che, per qualsiasi motivo, non potrebbero acconsentire personalmente e autonomamente all'obbligo di lavorare per TORTEL INDUSTRIES,<\/li><\/ul><p>e garantisce che eventuali fornitori e\/o subappaltatori rispettino gli stessi impegni.<\/p><p>Inoltre, TORTEL INDUSTRIES certifica di aver effettuato le dichiarazioni richieste dalle autorit\u00e0 sociali e fiscali e di aver fornito al Cliente, quando \u00e8 stabilito o domiciliato in Francia, i documenti richiesti ai sensi degli articoli L.8222-1, R.8222-1, D.8222-5, D.8254-2 e D.8254-4 del Codice del Lavoro francese o, quando \u00e8 stabilito o domiciliato all'estero ed \u00e8 coinvolto in Francia nell'esecuzione del Contratto, i documenti richiesti ai sensi degli articoli L.8222-1, L.8222-4, R.8222-1 e D.8222-7 del Codice del Lavoro francese.<\/p><p>TORTEL INDUSTRIES dichiara che tutti gli edifici che utilizza o gestisce rispettano le normative ad essi applicabili, in particolare per quanto riguarda la sicurezza, il rispetto dell'ambiente e la legislazione sugli stabilimenti classificati di qualsiasi tipo. In particolare, TORTEL INDUSTRIES certifica di rispettare in ogni momento le misure preventive applicabili allo stoccaggio e all'utilizzo di prodotti che possono rappresentare un pericolo per la sicurezza, la salute o l'igiene.<\/p><p>In conformit\u00e0 alle disposizioni legislative e regolamentari vigenti, TORTEL INDUSTRIES assicura che i Prodotti sono stati sottoposti a un controllo basato su un sistema che identifica, valuta e assicura il controllo dei pericoli significativi.<\/p><p>TORTEL INDUSTRIES si impegna inoltre a rispettare in particolare:<\/p><ul><li>Regolamento (CE) n. 1907\/2006 del Parlamento europeo e del Consiglio, del 18 dicembre 2006, concernente la registrazione, la valutazione, l'autorizzazione e la restrizione delle sostanze chimiche (REACH);<\/li><li>Direttiva europea 2002\/95\/CE del 27 gennaio 2003 sulla restrizione dell'uso di determinate sostanze pericolose nelle apparecchiature elettriche ed elettroniche, Direttiva europea 2002\/96\/CE del 27 gennaio 2003 sui rifiuti di apparecchiature elettriche ed elettroniche (RAEE) e Decreto 2005-829 del 20 luglio 2005 sulla composizione delle apparecchiature elettriche ed elettroniche e sullo smaltimento dei rifiuti di tali apparecchiature;<\/li><li>se applicabile alla societ\u00e0 in quanto societ\u00e0 le cui azioni sono ammesse a un mercato regolamentato, gli articoli L.225-102-1, paragrafo 5 e R.225-105 del Codice commerciale francese;<\/li><li>tutte le leggi e i regolamenti vigenti, come quelli relativi alla composizione, all'igiene e alla sicurezza alimentare (cfr. in particolare le direttive 2006\/141\/CE, 2000\/13\/CE, 1995\/2\/CEE, il regolamento 1333\/2008\/CE).<\/li><\/ul><p>Il tutto in modo da garantire che il Cliente non sia mai preoccupato a questo riguardo.<\/p><p>Se il Fornitore non rispetta questo impegno, l'Acquirente pu\u00f2 risolvere il rapporto commerciale per legge a causa di una grave violazione da parte del Fornitore di uno dei suoi obblighi essenziali. Tale risoluzione avverr\u00e0 entro trenta (30) giorni dalla messa in mora, senza alcun effetto, a condizione che la Merce possa essere sostituita, o immediatamente in caso contrario.<\/p><h4><strong>19. RESPONSABILIT\u00c0 SOCIALE D'IMPRESA<\/strong><\/h4><p>Le Parti si impegnano a mettere in atto misure volte a prevenire e individuare la commissione, in Francia o all'estero, di atti di corruzione o di traffico di influenza. A questo proposito, TORTEL INDUSTRIES si impegna e garantisce al Cliente:<\/p><ul><li>che rispetta e continuer\u00e0 a rispettare per tutta la durata del rapporto commerciale tutta la legislazione francese, europea e internazionale in vigore in materia di prevenzione e lotta alla corruzione e al traffico di influenza;<\/li><li>di aver messo in atto, o di voler mettere in atto entro un termine ragionevole, un sistema anticorruzione conforme alle disposizioni dell'articolo 17 della legge del 9 dicembre 2016 sulla trasparenza, la lotta alla corruzione e la modernizzazione della vita economica, nota come legge SAPIN II;<\/li><li>di non aver commesso, e di assicurarsi di non commettere in futuro, alcun atto che costituisca o possa costituire una violazione di tutta la legislazione anticorruzione applicabile, in particolare delle disposizioni dell'articolo 435-1 e seguenti del Codice penale francese;<\/li><li>di non essere oggetto di indagini amministrative o giudiziarie su fatti configurabili come corruzione pubblica o privata o traffico di influenze.<\/li><\/ul><p>Nell'ambito del suo obbligo di valutazione, il Cliente potr\u00e0 in qualsiasi momento richiedere a TORTEL INDUSTRIES la prova del rispetto dei requisiti della presente clausola e potr\u00e0 in qualsiasi momento, previa notifica e a proprie spese, effettuare o far effettuare audit. In caso di audit, TORTEL INDUSTRIES si impegna a collaborare e a fornire qualsiasi informazione e\/o documentazione che il Cliente possa richiedere per consentire l'esecuzione dell'audit.<\/p><p>L'inosservanza delle disposizioni della presente clausola costituir\u00e0 motivo di risoluzione automatica dell'Ordine per violazione di un obbligo essenziale del contratto e\/o del rapporto commerciale secondo i termini e le condizioni stabiliti nelle presenti CGV. Le Parti si assicurano e garantiscono che i loro dirigenti, dipendenti, affiliati e qualsiasi persona o societ\u00e0 che agisca per suo conto o in suo nome, nonch\u00e9 i subappaltatori, rispettino i suddetti obblighi e si impegnano a notificare senza indugio all'altra Parte qualsiasi richiesta, procedura o indagine a cui possa essere soggetta, direttamente o indirettamente, a causa di una violazione delle leggi francesi, europee o internazionali relative alla prevenzione e alla lotta contro la corruzione e il traffico di influenze.<\/p><h4><strong>20. LEGGE APPLICABILE - GIURISDIZIONE<\/strong><\/h4><p>I rapporti tra TORTEL INDUSTRIES e il Cliente sono disciplinati dal diritto francese.<\/p><p>In caso di controversia, i tribunali di Parigi avranno la giurisdizione esclusiva, indipendentemente dalla natura, dalla causa o dal luogo della controversia e dalle condizioni speciali di vendita, anche in caso di richiesta di garanzia o di pluralit\u00e0 di convenuti.<\/p><p>La Convenzione delle Nazioni Unite sui contratti di vendita internazionale di merci non si applica alle presenti Condizioni generali.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Conditions g\u00e9n\u00e9rales de ventes \u00a0 POLITIQUE DE CONFIDENTIALITE En vigueur au 24\/01\/2020 Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab\u00a0CGV\u00a0\u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab\u00a0Produits\u00a0\u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab\u00a0Client\u00a0\u00bb). Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab\u00a0Parties\u00a0\u00bb ou individuellement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-32","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Conditions g\u00e9n\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\/01\/2020Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab CGV \u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab Produits \u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab Client \u00bb).Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab Parties \u00bb ou individuellement la \u00ab Partie \u00bb.Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"STIMCARE - Stimule &amp; Soulage\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Conditions G\u00e9n\u00e9rales de Ventes - STIMCARE\" \/>\n\t\t<meta property=\"og:description\" content=\"Conditions g\u00e9n\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\/01\/2020Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab CGV \u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab Produits \u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab Client \u00bb).Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab Parties \u00bb ou individuellement la \u00ab Partie \u00bb.Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/stimcareonline.com\/wp-content\/uploads\/2022\/03\/SC-Logo-CMJN-copie.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/stimcareonline.com\/wp-content\/uploads\/2022\/03\/SC-Logo-CMJN-copie.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1016\" \/>\n\t\t<meta property=\"og:image:height\" content=\"142\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-03-04T10:54:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-04-20T19:09:25+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Stimcareonline\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Conditions G\u00e9n\u00e9rales de Ventes - STIMCARE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Conditions g\u00e9n\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\/01\/2020Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab CGV \u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab Produits \u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab Client \u00bb).Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab Parties \u00bb ou individuellement la \u00ab Partie \u00bb.Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/stimcareonline.com\/wp-content\/uploads\/2022\/03\/SC-Logo-CMJN-copie.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stimcareonline.com\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/#listItem\",\"name\":\"Conditions G\\u00e9n\\u00e9rales de Ventes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/#listItem\",\"position\":2,\"name\":\"Conditions G\\u00e9n\\u00e9rales de Ventes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/#organization\",\"name\":\"STIMCARE\",\"description\":\"Stimule & Soulage\",\"url\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/stimcareonline.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/stimcare-logo-black-300.png\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/#organizationLogo\",\"width\":300,\"height\":43},\"image\":{\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Stimcareonline\",\"https:\\\/\\\/www.instagram.com\\\/stimcare\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@stimcare6509\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/#webpage\",\"url\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/\",\"name\":\"Conditions G\\u00e9n\\u00e9rales de Ventes - STIMCARE\",\"description\":\"Conditions g\\u00e9n\\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\\\/01\\\/2020Les pr\\u00e9sentes conditions g\\u00e9n\\u00e9rales de vente (\\u00ab CGV \\u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \\u00ab Produits \\u00bb) effectu\\u00e9es par TORTEL INDUTRIES \\u00e0 ses clients (ci-apr\\u00e8s le \\u00ab Client \\u00bb).Le Client et le Fournisseur \\u00e9tant ci-apr\\u00e8s d\\u00e9sign\\u00e9s collectivement les \\u00ab Parties \\u00bb ou individuellement la \\u00ab Partie \\u00bb.Les pr\\u00e9sentes Conditions G\\u00e9n\\u00e9rales de\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/conditions-generales-de-ventes\\\/#breadcrumblist\"},\"datePublished\":\"2022-03-04T11:54:31+01:00\",\"dateModified\":\"2022-04-20T21:09:25+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/\",\"name\":\"STIMCARE\",\"description\":\"Stimule & Soulage\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/stimcareonline.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Conditions G\u00e9n\u00e9rales de Ventes - STIMCARE","description":"Conditions g\u00e9n\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\/01\/2020Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab CGV \u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab Produits \u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab Client \u00bb).Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab Parties \u00bb ou individuellement la \u00ab Partie \u00bb.Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de","canonical_url":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/stimcareonline.com\/it#listItem","position":1,"name":"Home","item":"https:\/\/stimcareonline.com\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/#listItem","name":"Conditions G\u00e9n\u00e9rales de Ventes"}},{"@type":"ListItem","@id":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/#listItem","position":2,"name":"Conditions G\u00e9n\u00e9rales de Ventes","previousItem":{"@type":"ListItem","@id":"https:\/\/stimcareonline.com\/it#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/stimcareonline.com\/it\/#organization","name":"STIMCARE","description":"Stimule & Soulage","url":"https:\/\/stimcareonline.com\/it\/","logo":{"@type":"ImageObject","url":"https:\/\/stimcareonline.com\/wp-content\/uploads\/2022\/04\/stimcare-logo-black-300.png","@id":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/#organizationLogo","width":300,"height":43},"image":{"@id":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Stimcareonline","https:\/\/www.instagram.com\/stimcare\/","https:\/\/www.youtube.com\/@stimcare6509"]},{"@type":"WebPage","@id":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/#webpage","url":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/","name":"Conditions G\u00e9n\u00e9rales de Ventes - STIMCARE","description":"Conditions g\u00e9n\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\/01\/2020Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab CGV \u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab Produits \u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab Client \u00bb).Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab Parties \u00bb ou individuellement la \u00ab Partie \u00bb.Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/stimcareonline.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/#breadcrumblist"},"datePublished":"2022-03-04T11:54:31+01:00","dateModified":"2022-04-20T21:09:25+02:00"},{"@type":"WebSite","@id":"https:\/\/stimcareonline.com\/it\/#website","url":"https:\/\/stimcareonline.com\/it\/","name":"STIMCARE","description":"Stimule & Soulage","inLanguage":"it-IT","publisher":{"@id":"https:\/\/stimcareonline.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"STIMCARE - Stimule &amp; Soulage","og:type":"article","og:title":"Conditions G\u00e9n\u00e9rales de Ventes - STIMCARE","og:description":"Conditions g\u00e9n\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\/01\/2020Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab CGV \u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab Produits \u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab Client \u00bb).Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab Parties \u00bb ou individuellement la \u00ab Partie \u00bb.Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de","og:url":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/","og:image":"https:\/\/stimcareonline.com\/wp-content\/uploads\/2022\/03\/SC-Logo-CMJN-copie.png","og:image:secure_url":"https:\/\/stimcareonline.com\/wp-content\/uploads\/2022\/03\/SC-Logo-CMJN-copie.png","og:image:width":1016,"og:image:height":142,"article:published_time":"2022-03-04T10:54:31+00:00","article:modified_time":"2022-04-20T19:09:25+00:00","article:publisher":"https:\/\/www.facebook.com\/Stimcareonline","twitter:card":"summary_large_image","twitter:title":"Conditions G\u00e9n\u00e9rales de Ventes - STIMCARE","twitter:description":"Conditions g\u00e9n\u00e9rales de ventes POLITIQUE DE CONFIDENTIALITEEn vigueur au 24\/01\/2020Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente (\u00ab CGV \u00bb) sont applicables pour toutes les commandes et livraisons de produits (les \u00ab Produits \u00bb) effectu\u00e9es par TORTEL INDUTRIES \u00e0 ses clients (ci-apr\u00e8s le \u00ab Client \u00bb).Le Client et le Fournisseur \u00e9tant ci-apr\u00e8s d\u00e9sign\u00e9s collectivement les \u00ab Parties \u00bb ou individuellement la \u00ab Partie \u00bb.Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de","twitter:image":"https:\/\/stimcareonline.com\/wp-content\/uploads\/2022\/03\/SC-Logo-CMJN-copie.png"},"aioseo_meta_data":{"post_id":"32","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-25 11:25:23","updated":"2025-06-10 11:09:29","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/stimcareonline.com\/it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tConditions G\u00e9n\u00e9rales de Ventes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/stimcareonline.com\/it"},{"label":"Conditions G\u00e9n\u00e9rales de Ventes","link":"https:\/\/stimcareonline.com\/it\/conditions-generales-de-ventes\/"}],"_links":{"self":[{"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/pages\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":5,"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/pages\/32\/revisions"}],"predecessor-version":[{"id":28688,"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/pages\/32\/revisions\/28688"}],"wp:attachment":[{"href":"https:\/\/stimcareonline.com\/it\/wp-json\/wp\/v2\/media?parent=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}